{"id":15148,"date":"2013-01-31T12:23:10","date_gmt":"2013-01-31T10:23:10","guid":{"rendered":"http:\/\/blog.steuer.org\/?p=15148"},"modified":"2013-03-25T12:27:07","modified_gmt":"2013-03-25T10:27:07","slug":"wie-wird-zahlungsunfahigkeit-einer-gmbh-ermittelt","status":"publish","type":"post","link":"https:\/\/www.steuerschroeder.de\/blog\/wie-wird-zahlungsunfahigkeit-einer-gmbh-ermittelt\/","title":{"rendered":"Wie wird Zahlungsunf\u00e4higkeit einer GmbH ermittelt?"},"content":{"rendered":"<p><strong>Wie wird Zahlungsunf\u00e4higkeit einer GmbH ermittelt?<\/strong><\/p>\n<p><strong>Kernaussage<\/strong><\/p>\n<p>Das GmbH-Gesetz bestimmt, dass eine GmbH im Falle der finanziellen Krise keine Zahlungen an ihre Gesellschafter ausf\u00fchren darf, wenn dies zur Zahlungsunf\u00e4higkeit und damit zur Insolvenzreife der GmbH f\u00fchrt. Hierzu hat der Bundesgerichtshof (BGH) aktuell entschieden, dass eine Zahlungsunf\u00e4higkeit der GmbH durch eine Zahlung an einen Gesellschafter dann nicht im Sinne des Gesetzes als verursacht gilt, wenn die GmbH bereits zahlungsunf\u00e4hig war.<\/p>\n<p><strong>Sachverhalt<\/strong><\/p>\n<p>Der Kl\u00e4ger und seine mittlerweile von ihm geschiedene Ehefrau, die alleinige Gesellschafter-Gesch\u00e4ftsf\u00fchrerin der beklagten GmbH ist, gew\u00e4hrten dieser 1995 ein Darlehen \u00fcber rd. 179.000 EUR. Die GmbH verpflichtete sich, das Darlehen bis sp\u00e4testens Ende 2005 zur\u00fcckzuzahlen, tat dies aber nicht. Der Kl\u00e4ger verlangt nun Hinterlegung des Darlehensbetrags nebst Zinsen zu seinen Gunsten und zu Gunsten seiner fr\u00fcheren Ehefrau. Die GmbH verweigert die R\u00fcckerstattung des Darlehens mit der Begr\u00fcndung, die R\u00fcckzahlung f\u00fchre zu ihrer Zahlungsunf\u00e4higkeit, so dass sie diese von Gesetzes wegen verweigern k\u00f6nne. Der Kl\u00e4ger unterlag vor dem Oberlandesgericht (OLG); der BGH hob das Urteil jedoch auf und verwies die Sache zur\u00fcck. Nach Ansicht der BGH-Richter durfte die GmbH die R\u00fcckerstattung nicht zur\u00fcckhalten.<\/p>\n<p><strong>Entscheidung<\/strong><\/p>\n<p>Die Zahlungsunf\u00e4higkeit einer GmbH wird durch eine Zahlung an den Gesellschafter nicht verursacht, wenn die Gesellschaft bereits zahlungsunf\u00e4hig ist. Das Gesetz verlangt, dass die konkrete Zahlung zur Zahlungsunf\u00e4higkeit f\u00fchren musste. Bei der Ermittlung der Zahlungsunf\u00e4higkeit ist eine f\u00e4llige Forderung des Gesellschafters in der Liquidit\u00e4tsbilanz zu ber\u00fccksichtigen. Nach der Rechtsprechung des BGH ist eine GmbH zahlungsunf\u00e4hig, wenn unter Ber\u00fccksichtigung f\u00e4lliger, d. h. ernsthaft eingeforderter Gesellschafterforderungen bereits eine Deckungsl\u00fccke von 10 % oder mehr besteht. In diesem Fall wird die Zahlungsunf\u00e4higkeit nicht durch die Zahlung an den Gesellschafter herbeigef\u00fchrt. Das Gesetz verlangt die Verursachung der Zahlungsunf\u00e4higkeit und stellt nicht auch auf die Vertiefung einer bereits eingetretenen Zahlungsunf\u00e4higkeit ab. Das OLG muss jetzt noch anhand einer aufzustellenden Liquidit\u00e4tsbilanz feststellen, ob die Darlehensr\u00fcckzahlung die Zahlungsunf\u00e4higkeit tats\u00e4chlich erst verursachen w\u00fcrde. Nur dann kann die GmbH die R\u00fcckzahlung verweigern.<\/p>\n<p><strong>Konsequenz<\/strong><\/p>\n<p>Das gesetzliche &#8222;(R\u00fcck)zahlungsverbot&#8220; f\u00fcr die GmbH korrespondiert mit der Haftung des Gesch\u00e4ftsf\u00fchrers. Zahlt er im Namen der GmbH verbotswidrig Betr\u00e4ge an die Gesellschafter aus und f\u00fchrt dies zur Zahlungsunf\u00e4higkeit der GmbH, haftet der Gesch\u00e4ftsf\u00fchrer gegen\u00fcber der GmbH f\u00fcr die Zahlungen. Er sollte daher Zahlungsfl\u00fcsse in der Krise immer genau dokumentieren, um sich im Ernstfall entlasten zu k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie wird Zahlungsunf\u00e4higkeit einer GmbH ermittelt? Kernaussage Das GmbH-Gesetz bestimmt, dass eine GmbH im Falle der finanziellen Krise keine Zahlungen an ihre Gesellschafter ausf\u00fchren darf, wenn dies zur Zahlungsunf\u00e4higkeit und damit zur Insolvenzreife der GmbH f\u00fchrt. Hierzu hat der Bundesgerichtshof (BGH) aktuell entschieden, dass eine Zahlungsunf\u00e4higkeit der GmbH durch eine Zahlung an einen Gesellschafter dann &hellip; <a href=\"https:\/\/www.steuerschroeder.de\/blog\/wie-wird-zahlungsunfahigkeit-einer-gmbh-ermittelt\/\" class=\"more-link\"><span class=\"screen-reader-text\">Wie wird Zahlungsunf\u00e4higkeit einer GmbH ermittelt?<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[2075],"_links":{"self":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/15148"}],"collection":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/comments?post=15148"}],"version-history":[{"count":0,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/15148\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/media?parent=15148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/categories?post=15148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/tags?post=15148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}