{"id":15356,"date":"2013-03-27T07:04:39","date_gmt":"2013-03-27T05:04:39","guid":{"rendered":"http:\/\/blog.steuer.org\/?p=15356"},"modified":"2023-08-25T09:54:45","modified_gmt":"2023-08-25T07:54:45","slug":"monatsbericht-des-bmf-marz-2013-2","status":"publish","type":"post","link":"https:\/\/www.steuerschroeder.de\/blog\/monatsbericht-des-bmf-marz-2013-2\/","title":{"rendered":"Monatsbericht des BMF M\u00e4rz 2013"},"content":{"rendered":"<p>Das\u00a0Bundesministerium der Finanzen (BMF)\u00a0hat heute seinen Monatsbericht f\u00fcr M\u00e4rz 2013 ver\u00f6ffentlicht:<\/p>\n<p>\u201cDas Bundeskabinett hat am 13. M\u00e4rz 2013 die Eckwerte zum Bundeshaushalt 2014 und zum Finanzplan bis 2017 beschlossen. Diese Eckwerte unterstreichen den konsequenten Konsolidierungskurs der Bundesregierung. Mit dem Bundeshaushalt 2014 wird zum ersten Mal seit Jahrzehnten ein nachhaltig ausgeglichener Haushalt mit einem strukturellen Defizit von Null vorgelegt. Ab 2015 schreibt der Bundeshaushalt \u201ceine schwarze Null\u201d \u2013 kommt also g\u00e4nzlich ohne Einnahmen aus neuen Krediten aus. In der Rubrik \u201cForum Finanzpolitik\u201d wird als weiterer Gastbeitrag dieser Reihe ein Artikel von Vitor Gaspar, Finanzminister der Republik Portugal, zur Anpassung Portugals als Mitglied im Euroraum ver\u00f6ffentlicht. Dar\u00fcber hinaus wird in der Rubrik \u201cAnalysen und Berichte\u201d des Monatsberichts des BMF \u00fcber den Tragf\u00e4higkeitsbericht 2012 der EU-Kommission informiert, \u00fcber die Ergebnisse der Gesch\u00e4ftsstatistik der Kraftfahrzeugsteuer (PKW) f\u00fcr das Jahr 2012 berichtet und ein Bericht zum Treffen der G20-Finanzminister im Februar in Moskau vorgelegt.<\/p>\n<p>Editorial<br \/>\n\u00dcberblick zur aktuellen Lage<br \/>\nForum Finanzpolitik<br \/>\nV\u00edtor Gaspar, portugiesischer Finanzminister: Anpassung im Euroraum: Portugal als Programmland<br \/>\nAnalysen und Berichte<br \/>\nEckwertebeschluss zum Regierungsentwurf f\u00fcr den Bundeshaushalt 2014 und die Finanzplanung bis zum Jahr 2017<br \/>\nDer Tragf\u00e4higkeitsbericht 2012 der EU-Kommission<br \/>\nGesch\u00e4ftsstatistik Kraftfahrzeugsteuer<br \/>\nTreffen der G20-Finanzminister und Notenbankgouverneure am 15. und 16. Februar 2013 in Moskau<br \/>\nAktuelle Wirtschafts- und Finanzlage<br \/>\nKonjunkturentwicklung aus finanzpolitischer Sicht<br \/>\nSteuereinnahmen von Bund und L\u00e4ndern im Februar 2013<br \/>\nEntwicklung des Bundeshaushalts bis einschlie\u00dflich Februar 2013<br \/>\nEntwicklung der L\u00e4nderhaushalte bis Dezember 2012<br \/>\nFinanzm\u00e4rkte und Kreditaufnahme des Bundes<br \/>\nEurop\u00e4ische Wirtschafts- und Finanzpolitik<br \/>\nTermine, Publikationen<br \/>\nStatistiken und Dokumentationen<br \/>\n\u00dcbersichten zur finanzwirtschaftlichen Entwicklung<br \/>\n\u00dcbersichten zur Entwicklung der L\u00e4nderhaushalte<br \/>\nKennzahlen zur gesamtwirtschaftlichen Entwicklung<br \/>\nMonatsbericht des BMF (M\u00e4rz 2013) (PDF, 2,7 MB)\u201d<\/p>\n<p>Bundesministerium der Finanzen (BMF)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das\u00a0Bundesministerium der Finanzen (BMF)\u00a0hat heute seinen Monatsbericht f\u00fcr M\u00e4rz 2013 ver\u00f6ffentlicht: \u201cDas Bundeskabinett hat am 13. M\u00e4rz 2013 die Eckwerte zum Bundeshaushalt 2014 und zum Finanzplan bis 2017 beschlossen. Diese Eckwerte unterstreichen den konsequenten Konsolidierungskurs der Bundesregierung. Mit dem Bundeshaushalt 2014 wird zum ersten Mal seit Jahrzehnten ein nachhaltig ausgeglichener Haushalt mit einem strukturellen Defizit &hellip; <a href=\"https:\/\/www.steuerschroeder.de\/blog\/monatsbericht-des-bmf-marz-2013-2\/\" class=\"more-link\"><span class=\"screen-reader-text\">Monatsbericht des BMF M\u00e4rz 2013<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[2105],"_links":{"self":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/15356"}],"collection":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/comments?post=15356"}],"version-history":[{"count":0,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/15356\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/media?parent=15356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/categories?post=15356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/tags?post=15356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}