{"id":19800,"date":"2013-04-06T11:28:58","date_gmt":"2013-04-06T09:28:58","guid":{"rendered":"http:\/\/blog.steuer.org\/?p=19800"},"modified":"2018-03-22T10:41:54","modified_gmt":"2018-03-22T08:41:54","slug":"steuererklarungsfristen-2012","status":"publish","type":"post","link":"https:\/\/www.steuerschroeder.de\/blog\/steuererklarungsfristen-2012\/","title":{"rendered":"Steuererkl\u00e4rungsfristen 2012"},"content":{"rendered":"<p><strong>Abgabefrist f\u00fcr Steuererkl\u00e4rungen<\/strong><\/p>\n<p>F\u00fcr das Kalenderjahr 2012 sind folgende Erkl\u00e4rungen bis zum 31.5.2013 bei den Finanz\u00e4mtern abzugeben: die Erkl\u00e4rungen zur Einkommensteuer, einschlie\u00dflich der Erkl\u00e4rungen zur gesonderten sowie zur gesonderten und einheitlichen Feststellung von Grundlagen f\u00fcr die Einkommensbesteuerung sowie zur gesonderten Feststellung des verbleibenden Verlustvortrags. Ferner die Erkl\u00e4rungen zur K\u00f6rperschaftsteuer, einschlie\u00dflich der Erkl\u00e4rungen zu gesonderten Feststellungen von Besteuerungsgrundlagen, die in Zusammenhang mit der K\u00f6rperschaftsteuerveranlagung durchzuf\u00fchren sind, sowie f\u00fcr die Zerlegung der K\u00f6rperschaftsteuer. Ebenfalls bis zu diesem Datum abzugeben sind die Erkl\u00e4rungen zur Gewerbesteuer, einschlie\u00dflich der Erkl\u00e4rungen zur gesonderten Feststellung des vortragsf\u00e4higen Gewerbeverlustes und zur gesonderten Feststellung des Zuwendungsvortrags sowie f\u00fcr die Zerlegung des Steuermessbetrags. Schlie\u00dflich auch die <a href=\"http:\/\/www.steuerschroeder.de\/steuererklaerung\/Umsatzsteuererklaerung.html\" target=\"_blank\">Erkl\u00e4rungen zur Umsatzsteuer<\/a> sowie zur gesonderten oder zur gesonderten und einheitlichen Feststellung nach \u00a7 18 des Au\u00dfensteuergesetzes.<\/p>\n<p><strong>Sonderfrist<\/strong><\/p>\n<p>Bei Steuerpflichtigen, die den Gewinn aus Land- und Forstwirtschaft nach einem vom Kalenderjahr abweichenden Wirtschaftsjahr ermitteln, endet die Frist nicht vor Ablauf des f\u00fcnften Monats, der auf den Schluss des Wirtschaftsjahres 2012\/2013 folgt.<\/p>\n<p><strong>Fristverl\u00e4ngerung<\/strong><\/p>\n<p>Sofern die vorbezeichneten Steuererkl\u00e4rungen durch Personen, Gesellschaften, Verb\u00e4nde, Vereinigungen, Beh\u00f6rden oder K\u00f6rperschaften im Sinne der \u00a7\u00a7 3 und 4 StBerG angefertigt werden, wird die Frist allgemein bis zum 31.12.2013 verl\u00e4ngert. Bei Steuererkl\u00e4rungen f\u00fcr Steuerpflichtige, die den Gewinn aus Land- und Forstwirtschaft nach einem vom Kalenderjahr abweichenden Wirtschaftsjahr ermitteln, tritt an die Stelle des 31.12.2013 der 31.5.2014. Es bleibt den Finanz\u00e4mtern vorbehalten, Erkl\u00e4rungen mit angemessener Frist f\u00fcr einen Zeitpunkt vor Ablauf der allgemein verl\u00e4ngerten Frist anzufordern. Von dieser M\u00f6glichkeit soll insbesondere Gebrauch gemacht werden, wenn f\u00fcr den vorangegangenen Veranlagungszeitraum die erforderlichen Erkl\u00e4rungen versp\u00e4tet oder nicht abgegeben wurden. Ferner dann, wenn f\u00fcr den vorangegangenen Veranlagungszeitraum kurz vor Abgabe der Erkl\u00e4rung bzw. vor dem Ende der Karenzzeit nachtr\u00e4gliche Vorauszahlungen festgesetzt wurden oder sich aus der Veranlagung f\u00fcr den vorangegangenen Veranlagungszeitraum eine hohe Abschlusszahlung ergeben hat. Des Weiteren soll von der M\u00f6glichkeit Gebrauch gemacht werden, wenn hohe Abschlusszahlungen erwartet werden oder f\u00fcr Beteiligte an Gesellschaften und Gemeinschaften Verluste festzustellen sind oder die Arbeitslage der Finanz\u00e4mter es erfordert. Im \u00dcbrigen wird davon ausgegangen, dass die Erkl\u00e4rungen laufend fertig gestellt und unverz\u00fcglich eingereicht werden. Aufgrund begr\u00fcndeter Einzelantr\u00e4ge kann die Frist f\u00fcr die Abgabe der Steuererkl\u00e4rungen bis zum 28.2.2014 bzw. in den F\u00e4llen, in denen die vorbezeichnete Sonderfrist gilt, bis zum 31.7.2014 verl\u00e4ngert werden. Eine weitergehende Fristverl\u00e4ngerung kommt grunds\u00e4tzlich nicht in Betracht. Die allgemeine Fristverl\u00e4ngerung gilt nicht f\u00fcr Antr\u00e4ge auf Steuerverg\u00fctungen. Sie gilt auch nicht f\u00fcr die Abgabe von Umsatzsteuererkl\u00e4rungen, wenn die gewerbliche oder berufliche T\u00e4tigkeit mit Ablauf des 31.12.2012 endete. Hat die gewerbliche oder berufliche T\u00e4tigkeit vor dem 31.12.2012 geendet, ist die Umsatzsteuererkl\u00e4rung f\u00fcr das Kalenderjahr einen Monat nach Beendigung der gewerblichen oder beruflichen T\u00e4tigkeit abzugeben.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abgabefrist f\u00fcr Steuererkl\u00e4rungen F\u00fcr das Kalenderjahr 2012 sind folgende Erkl\u00e4rungen bis zum 31.5.2013 bei den Finanz\u00e4mtern abzugeben: die Erkl\u00e4rungen zur Einkommensteuer, einschlie\u00dflich der Erkl\u00e4rungen zur gesonderten sowie zur gesonderten und einheitlichen Feststellung von Grundlagen f\u00fcr die Einkommensbesteuerung sowie zur gesonderten Feststellung des verbleibenden Verlustvortrags. Ferner die Erkl\u00e4rungen zur K\u00f6rperschaftsteuer, einschlie\u00dflich der Erkl\u00e4rungen zu gesonderten Feststellungen &hellip; <a href=\"https:\/\/www.steuerschroeder.de\/blog\/steuererklarungsfristen-2012\/\" class=\"more-link\"><span class=\"screen-reader-text\">Steuererkl\u00e4rungsfristen 2012<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1463,1689,1469,4,1730,63,1],"tags":[2290],"_links":{"self":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/19800"}],"collection":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/comments?post=19800"}],"version-history":[{"count":0,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/19800\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/media?parent=19800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/categories?post=19800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/tags?post=19800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}