{"id":51827,"date":"2019-06-08T13:32:36","date_gmt":"2019-06-08T11:32:36","guid":{"rendered":"http:\/\/www.steuerschroeder.de\/blog\/?p=51827"},"modified":"2019-06-08T13:32:36","modified_gmt":"2019-06-08T11:32:36","slug":"bfd-seminarleiterin-rentenversicherungsfrei","status":"publish","type":"post","link":"https:\/\/www.steuerschroeder.de\/blog\/bfd-seminarleiterin-rentenversicherungsfrei\/","title":{"rendered":"BFD-Seminarleiterin rentenversicherungsfrei"},"content":{"rendered":"<article>\n<h2>Gemeinn\u00fctziger Tr\u00e4ger muss keine Sozialabgaben f\u00fcr Studentin tragen<\/h2>\n<div id=\"vorspann\">\n<p>Das Landessozialgericht (LSG) Nordrhein-Westfalen hat in seinem j\u00fcngst rechtskr\u00e4ftig gewordenen Urteil vom 17.10.2018 best\u00e4tigt, dass eine T\u00e4tigkeit als Seminarleiterin anl\u00e4sslich der p\u00e4dagogischen Begleitung im Bundesfreiwilligendienst (BFD) nicht der Versicherungspflicht in der gesetzlichen Rentenversicherung unterliegt (Az. L 8 R 660\/16).<\/p>\n<\/div>\n<\/article>\n<article>Die Kl\u00e4gerin ist eine gemeinn\u00fctzige Gesellschaft, deren Gesellschaftszweck u. a. in der Betreuung hilfsbed\u00fcrftiger Menschen besteht. Hinter ihr steht ein Wohlfahrtsverband, der Freiwilligendienste u. a. in der Form des BFD anbietet. Im Rahmen der hierf\u00fcr einschl\u00e4gigen gesetzlichen Regelungen erfolgt eine p\u00e4dagogische Begleitung mit dem Ziel, den Teilnehmern soziale, \u00f6kologische, kulturelle und interkulturelle Kompetenzen zu vermitteln und ihr Verantwortungsbewusstsein f\u00fcr das Gemeinwohl zu st\u00e4rken. Die Kl\u00e4gerin schloss hierzu mit der beigeladenen Studentin Honorarvertr\u00e4ge \u00fcber die \u00dcbernahme von Seminarleitungen ab.<\/p>\n<p>Der beklagte Rentenversicherungstr\u00e4ger stellte die Versicherungspflicht der Beigeladenen in der Rentenversicherung fest. Hiergegen wandte sich die Kl\u00e4gerin auch in der Berufungsinstanz mit Erfolg. Das LSG hat festgestellt, dass die Beigeladene nicht auf Grund eines abh\u00e4ngigen Besch\u00e4ftigungsverh\u00e4ltnisses als Dozentin rentenversicherungspflichtig gewesen sei.<\/p>\n<p>In der Gesamtabw\u00e4gung spr\u00e4chen die zwischen der Kl\u00e4gerin und der Beigeladenen getroffenen vertraglichen Vereinbarungen und deren tats\u00e4chliche Umsetzung \u00fcberwiegend f\u00fcr eine selbst\u00e4ndige T\u00e4tigkeit. Weisungsbefugnisse kraft derer die Kl\u00e4gerin befugt gewesen w\u00e4re, gegen\u00fcber der Beigeladenen Anordnungen in inhaltlicher, zeitlicher und \u00f6rtlicher Hinsicht zu erteilen, h\u00e4tten die an der Auftragsbeziehung Beteiligten nur in sehr eingeschr\u00e4nktem Umfang vereinbart. Indizien, die die Annahme einer Eingliederung der Beigeladenen in die Arbeitsorganisation der Kl\u00e4gerin tragen w\u00fcrden, seien den getroffenen Vereinbarungen ebenfalls nicht in einem eine abh\u00e4ngige Besch\u00e4ftigung pr\u00e4genden Umfang zu entnehmen. Die p\u00e4dagogische Begleitung der Freiwilligen obliege in erster Linie den hauptamtlichen p\u00e4dagogischen Fachkr\u00e4ften, deren vorrangige Verantwortung etwa in dem p\u00e4dagogischen Rahmenkonzept der Kl\u00e4gerin deutlich werde.<\/p>\n<div class=\"clearfix\"><\/div>\n<\/article>\n<p id=\"source\">Quelle: LSG Nordrhein-Westfalen, Pressemitteilung vom 04.06.2019 zum Urteil L 8 R 660\/16 vom 17.10.2018 (rkr)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemeinn\u00fctziger Tr\u00e4ger muss keine Sozialabgaben f\u00fcr Studentin tragen Das Landessozialgericht (LSG) Nordrhein-Westfalen hat in seinem j\u00fcngst rechtskr\u00e4ftig gewordenen Urteil vom 17.10.2018 best\u00e4tigt, dass eine T\u00e4tigkeit als Seminarleiterin anl\u00e4sslich der p\u00e4dagogischen Begleitung im Bundesfreiwilligendienst (BFD) nicht der Versicherungspflicht in der gesetzlichen Rentenversicherung unterliegt (Az. L 8 R 660\/16). Die Kl\u00e4gerin ist eine gemeinn\u00fctzige Gesellschaft, deren Gesellschaftszweck &hellip; <a href=\"https:\/\/www.steuerschroeder.de\/blog\/bfd-seminarleiterin-rentenversicherungsfrei\/\" class=\"more-link\"><span class=\"screen-reader-text\">BFD-Seminarleiterin rentenversicherungsfrei<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1730],"tags":[],"_links":{"self":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/51827"}],"collection":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/comments?post=51827"}],"version-history":[{"count":0,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/posts\/51827\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/media?parent=51827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/categories?post=51827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/blog\/wp-json\/wp\/v2\/tags?post=51827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}