{"id":24777,"date":"2013-02-02T16:25:55","date_gmt":"2013-02-02T14:25:55","guid":{"rendered":"http:\/\/steuer.org\/?p=24777"},"modified":"2020-09-14T10:38:40","modified_gmt":"2020-09-14T08:38:40","slug":"r-b-109-2-ermittlung-des-substanzwerts","status":"publish","type":"post","link":"https:\/\/www.steuerschroeder.de\/steuer\/r-b-109-2-ermittlung-des-substanzwerts\/","title":{"rendered":"R B 109.2 Ermittlung des Substanzwerts"},"content":{"rendered":"<h2><strong>R B 109.2 Ermittlung des Substanzwerts<\/strong><\/h2>\n<p>(1) Bei der\u00a0<strong>Ermittlung des Substanzwerts<\/strong>\u00a0ist das Betriebsverm\u00f6gen mit dem Wert zum Bewertungsstichtag zugrunde zu legen.<\/p>\n<p>(2)\u00a0<sup>1<\/sup>Stimmt der Bewertungsstichtag nicht mit dem Schluss des Wirtschaftsjahrs \u00fcberein, auf den der Betrieb einen regelm\u00e4\u00dfigen j\u00e4hrlichen Abschluss macht, und erstellt der Betrieb keinen Zwischenabschluss, der den Grunds\u00e4tzen der Bilanzkontinuit\u00e4t entspricht, kann aus Vereinfachungsgr\u00fcnden der\u00a0<strong>Wert des Betriebsverm\u00f6gens zum Bewertungsstichtag<\/strong>\u00a0aus der auf den Schluss des letzten vor dem Bewertungsstichtag endenden Wirtschaftsjahrs erstellten Verm\u00f6gensaufstellung\u00a0<strong>abgeleitet<\/strong>\u00a0werden (Absatz 3), sofern dies im Einzelfall nicht zu unangemessenen Ergebnissen f\u00fchrt und deshalb eine besondere Ermittlung des Substanzwerts auf den Bewertungsstichtag vorzunehmen ist.\u00a0<sup>2<\/sup>Dabei ist zun\u00e4chst der Saldo der gemeinen Werte derjenigen Wirtschaftsg\u00fcter, sonstigen aktiven Ans\u00e4tze, Schulden und sonstigen Abz\u00fcge auf den Abschlusszeitpunkt zu bilden, die bei der Ermittlung des Substanzwerts des Betriebs anzusetzen sind\u00a0<strong>(<em>Ausgangswert<\/em>)<\/strong>.<\/p>\n<p>(3)\u00a0<sup>1<\/sup>Aus dem <strong>Ausgangswert<\/strong> (Absatz 2) ist der Wert des Betriebsverm\u00f6gens auf den Bewertungsstichtag unter vereinfachter Ber\u00fccksichtigung der Ver\u00e4nderungen bis zum Bewertungsstichtag abzuleiten.\u00a0<sup>2<\/sup>Als\u00a0<strong>Korrekturen<\/strong>\u00a0kommen insbesondere in Betracht:<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\">1.<\/td>\n<td valign=\"top\"><sup>1<\/sup>Hinzurechnung des Gewinns und der Einlagen sowie Abrechnung des Verlustes und der Entnahmen, die auf den Zeitraum vom letzten Bilanzstichtag vor dem Bewertungsstichtag bis zum Bewertungsstichtag entfallen.\u00a0<sup>2<\/sup>Auszugehen ist dabei vom Gewinn laut Steuerbilanz.\u00a0<sup>3<\/sup>Der Gewinn oder Verlust ist zu korrigieren, soweit darin <a title=\"Abscheibungen\" href=\"https:\/\/www.steuerschroeder.de\/Steuerrechner\/AfA.html\">Abschreibungen<\/a> (Normal-AfA, erh\u00f6hte AfA, Sonderabschreibungen, Teilwertabschreibungen) oder Aufwendungen auf betrieblichen Grundbesitz (Grund und Boden, Betriebsgeb\u00e4ude, Au\u00dfenanlagen, sonstige wesentliche Bestandteile und Zubeh\u00f6r) enthalten sind, die das Ergebnis gemindert haben, mit dem Wertansatz der Betriebsgrundst\u00fccke aber abgegolten sind; f\u00fcr Teilwertzuschreibungen gilt dies entsprechend.\u00a0<sup>4<\/sup>R B 11.4 Absatz 3 Nummer 1 Satz 4 gilt entsprechend.\u00a0<sup>5<\/sup>Gewinn oder Verlust und Abschreibungen oder andere Aufwendungen bis zum Bewertungsstichtag sind, soweit dies nicht im Einzelfall zu unangemessenen Ergebnissen f\u00fchrt, zeitanteilig aus den entsprechenden Jahresbetr\u00e4gen zu berechnen;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\">2.<\/td>\n<td valign=\"top\">Ber\u00fccksichtigung von Verm\u00f6gens\u00e4nderungen infolge Ver\u00e4u\u00dferung oder Erwerb von Anlageverm\u00f6gen, insbesondere von Betriebsgrundst\u00fccken, Wertpapieren, Anteilen und Genussscheinen von Kapitalgesellschaften und Beteiligungen an Personengesellschaften, soweit sie sich nicht bereits nach Nummer 1 ausgewirkt haben.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>(4)\u00a0<sup>1<\/sup>Der Erwerber von Betriebsverm\u00f6gen hat nach amtlichem Vordruck eine\u00a0<strong>Verm\u00f6gensaufstellung<\/strong>\u00a0auf den Bewertungsstichtag als Anlage zur Feststellungserkl\u00e4rung abzugeben, aus der sich die f\u00fcr die Wertermittlung erforderlichen Angaben ergeben.\u00a0<sup>2<\/sup>Dies gilt unabh\u00e4ngig von der f\u00fcr ertragsteuerrechtliche Zwecke gew\u00e4hlten Gewinnermittlungsart.<\/p>\n<p>Weitere Informationen zur <a title=\"Bewertung zum Substanzwert\" href=\"http:\/\/www.steuerschroeder.de\/Immobilienbewertung.html\">Bewertung und Substanzwert<\/a> &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R B 109.2 Ermittlung des Substanzwerts (1) Bei der\u00a0Ermittlung des Substanzwerts\u00a0ist das Betriebsverm\u00f6gen mit dem Wert zum Bewertungsstichtag zugrunde zu legen. (2)\u00a01Stimmt der Bewertungsstichtag nicht mit dem Schluss des Wirtschaftsjahrs \u00fcberein, auf den der Betrieb einen regelm\u00e4\u00dfigen j\u00e4hrlichen Abschluss macht, und erstellt der Betrieb keinen Zwischenabschluss, der den Grunds\u00e4tzen der Bilanzkontinuit\u00e4t entspricht, kann aus Vereinfachungsgr\u00fcnden &hellip; <a href=\"https:\/\/www.steuerschroeder.de\/steuer\/r-b-109-2-ermittlung-des-substanzwerts\/\" class=\"more-link\"><span class=\"screen-reader-text\">R B 109.2 Ermittlung des Substanzwerts<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2002],"class_list":["post-24777","post","type-post","status-publish","format-standard","hentry","category-steuer","tag-substanzwert"],"_links":{"self":[{"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/posts\/24777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/comments?post=24777"}],"version-history":[{"count":0,"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/posts\/24777\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/media?parent=24777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/categories?post=24777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.steuerschroeder.de\/steuer\/wp-json\/wp\/v2\/tags?post=24777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}